{"id":5124837,"date":"2008-11-28T09:27:12","date_gmt":"2008-11-28T09:27:12","guid":{"rendered":"http:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2008\/11\/28\/buy-nothing-day-5124837\/"},"modified":"2008-11-28T09:27:12","modified_gmt":"2008-11-28T09:27:12","slug":"buy-nothing-day-5124837","status":"publish","type":"post","link":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2008\/11\/28\/buy-nothing-day-5124837\/","title":{"rendered":"Buy-nothing-day 2008"},"content":{"rendered":"<p>Morgen bleibt hier das Portemonnaie kalt, da haben wir n\u00e4mlich den <a href=\"http:\/\/de.wikipedia.org\/wiki\/Kauf-Nix-Tag\" target=\"_blank\">&#8222;Kauf-nix-Tag&#8220;<\/a> bzw. &#8222;Buy-nothing-day&#8220;.<\/p>\n<p>Das bedeutet, dass ich morgen nichts kaufen werde (von einer Zeitung mal abgesehen, die lasse ich mir grad&#8216; noch so durchgehen), ganz besonders nat\u00fcrlich keinen Schnick- schnack, den sowieso keiner braucht.<\/p>\n<p>Das wollt&#8216; ich eigentlich nur mal eben erz\u00e4hlen&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morgen bleibt hier das Portemonnaie kalt, da haben wir n\u00e4mlich den &#8222;Kauf-nix-Tag&#8220; bzw. &#8222;Buy-nothing-day&#8220;. Das bedeutet, dass ich morgen nichts kaufen werde (von einer Zeitung mal abgesehen, die lasse ich mir grad&#8216; noch so durchgehen), ganz besonders nat\u00fcrlich keinen Schnick- schnack, den sowieso keiner braucht. Das wollt&#8216; ich eigentlich nur mal eben erz\u00e4hlen&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[1],"tags":[12,40,2],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6SDtE-lvcF","_links":{"self":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/5124837"}],"collection":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/comments?post=5124837"}],"version-history":[{"count":0,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/5124837\/revisions"}],"wp:attachment":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/media?parent=5124837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/categories?post=5124837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/tags?post=5124837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}