{"id":4523319,"date":"2008-07-31T07:30:40","date_gmt":"2008-07-31T07:30:40","guid":{"rendered":"http:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2008\/07\/31\/eigentlich-4523319\/"},"modified":"2008-07-31T07:30:40","modified_gmt":"2008-07-31T07:30:40","slug":"eigentlich-4523319","status":"publish","type":"post","link":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2008\/07\/31\/eigentlich-4523319\/","title":{"rendered":"Eigentlich&#8230;"},"content":{"rendered":"<p class=\"MsoNormal\">\u2026 ist es ja sehr sch\u00f6n, abends ins Bett zu gehen und dort schon ungeduldig erwartet zu werden. Das passiert mir jetzt seit Tagen. Aber es gef\u00e4llt mir nicht. Muss an mir liegen. <\/p>\n<p class=\"MsoNormal\">In mein Schlafzimmer ist n\u00e4mlich eine un<em>sicht<\/em>bare und sogar un<em>h\u00f6r<\/em>bare M\u00fccke eingezo-<br \/>gen. Jeden Abend gucke ich \u00fcberall genau nach, ob ich sie diesmal endlich finde, aber &#8217;s ist jedes Mal Essig. Auch Rufen und Locken mit entbl\u00f6\u00dftem Unterarm n\u00fctzt gar nix, &#8211; ich krieg\u2019 sie einfach nicht zu sehen. Dabei m\u00fcsste das Vieh eigentlich inzwischen fast so gro\u00df sein wie ein Sperling oder so! Schlie\u00dflich wache ich jeden Morgen mit wieder neuen Pieksp\u00fcnkten auf. Dass ich ein Kilo abgenommen habe, ist bestimmt auch kein Zufall. <\/p>\n<p class=\"MsoNormal\">Bezeichnenderweise habe in den letzten Tagen auch noch einen lustigen Roman gelesen, in dem sich\u2019s um Vampire dreht&#8230; Immerhin habe ich nun eine ungef\u00e4hre Vorstellung davon gewonnen, wie die M\u00fccke wohl <em>vonwoausauchimmer<\/em> auf mich guckt, wenn ich schlafend auf der Matte liege: \u201eIch bin reich! Ich bin reich!!! Alles meins! H\u00e4h\u00e4h\u00e4h\u00e4!!! Ich bin unermesslich reich und unsterblich!\u201c<\/p>\n<p class=\"MsoNormal\">Ich \u00fcberlege jetzt ernsthaft, mir aus Schaschlikst\u00e4bchen mal so kleine Holzpfl\u00f6cke zu schnitzen&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2026 ist es ja sehr sch\u00f6n, abends ins Bett zu gehen und dort schon ungeduldig erwartet zu werden. Das passiert mir jetzt seit Tagen. Aber es gef\u00e4llt mir nicht. Muss an mir liegen. In mein Schlafzimmer ist n\u00e4mlich eine unsichtbare und sogar unh\u00f6rbare M\u00fccke eingezo-gen. Jeden Abend gucke ich \u00fcberall genau nach, ob ich sie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[1],"tags":[2,11,3,58],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6SDtE-iYIL","_links":{"self":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/4523319"}],"collection":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/comments?post=4523319"}],"version-history":[{"count":0,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/4523319\/revisions"}],"wp:attachment":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/media?parent=4523319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/categories?post=4523319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/tags?post=4523319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}