{"id":3451085,"date":"2007-12-16T23:01:00","date_gmt":"2007-12-16T23:01:00","guid":{"rendered":"http:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2007\/12\/16\/17_dezember3451085\/"},"modified":"2007-12-16T23:01:00","modified_gmt":"2007-12-16T23:01:00","slug":"17_dezember3451085","status":"publish","type":"post","link":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2007\/12\/16\/17_dezember3451085\/","title":{"rendered":"17. Dezember"},"content":{"rendered":"<p><a href=\"#\" title=\"stern17\"><img src=\"http:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-content\/uploads\/2007\/12\/2216646_dc1a350912_s.jpeg\" alt=\"stern17\" hspace=\"5\" vspace=\"5\" align=\"right\"><\/a><span>Da auch <\/span><a href=\"#\">Trithemius<\/a><span> mir gleich ganz sch\u00f6n viele Fragen gestellt hat, fasse ich heute mal drei davon zusammen, denn das bietet sich geradezu an. Er m\u00f6chte n\u00e4mlich <font color=\"#cc3333\"><strong>wissen<\/strong><\/font>:<\/span>      <\/p>\n<p class=\"MsoNormal\"><span><font color=\"#cc3333\"><em><strong>&#8222;Bist du Schr\u00f6der in Hannover schon begegnet?<br \/>Was ist mit der Albrecht-Bagage? Und geisterte <br \/>nicht auch Herr Dosenpfand in Hannover herum?&#8220;<\/strong><\/em><\/font><br \/><!--[if !supportLineBreakNewLine]--><br \/><!--[endif]--><font color=\"#cc3333\"><strong>Antwort:<\/strong><\/font><\/span><\/p>\n<p class=\"MsoNormal\"><span>Erstmal vorweg:<\/span><\/p>\n<p class=\"MsoNormal\"><span>&#8211; Wer <strong>Schr\u00f6der <\/strong>ist, wei\u00df ja vielleicht noch der Eine oder die Andere.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&#8211; <strong>Ernst Albrecht<\/strong> war mal Ministerpr\u00e4sident von Niedersachsen, hat uns in dieser Zeit jede Menge Atomm\u00fcll eingebrockt, und ist au\u00dferdem der Vater von reichlich Kindern, eins davon hei\u00dft \u00fcbrigens <em>Ursula von der Leyen<\/em> und will Kinder als Alkoholkauf-Spione einset-<br \/>zen. Herr Albrecht war lange Ministerpr\u00e4sident (14 Jahre), hat mich als Kind mit seinem ber\u00fchmten Gutsherrengrinsen ziemlich angestrengt, und wurde dann damals von Gerhard Schr\u00f6der abgel\u00f6st. Das nur zur Erkl\u00e4rung.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&#8211; Herr Dosenpfand kann ja nur <strong>J\u00fcrgen Trittin<\/strong> sein, der tats\u00e4chlich auch lange in Hannover herumgewerkelt hat. Allerdings hatte er hier noch eine Schuhb\u00fcrste im Gesicht, die ich im Geiste immer noch jedes Mal hinzuf\u00fcge, wenn ich sein Gesicht irgendwo abgebildet sehe.<\/span><\/p>\n<p class=\"MsoNormal\">Und, na klar, kenne ich die alle pers\u00f6nlich, Hannover ist ja eher klein. Nee, stimmt gar nicht, aber ich kann tats\u00e4chlich von allen sagen, dass ich sie schon mal live vor der Nase hatte. Allerdings ist dabei nie was Spektakul\u00e4res passiert, &#8211; schade eigentlich. In den 90ern habe ich n\u00e4mlich ziemlich viel gekellnert. Das lag daran, dass ich damals mit einem Koch verbandelt war, der hat mich da mit reingezogen&#8230; Und irgendwie bin ich wohl \u00f6fter mal dahin geraten, wo &#8222;man&#8220; eben hinging, wenn man H\u00fcngerchen hatte. Kann ich ja nix f\u00fcr.<\/p>\n<p class=\"MsoNormal\">Es muss so 1994 gewesen sein, als ich in einem italienischen Restaurant besch\u00e4ftigt war. Eines Mittags tauchte dort Gerhard Schr\u00f6der, damals noch Ministerpr\u00e4sident, mit ein paar Bodyguards auf und bestellte Spaghetti Bolognese. (Er war ja noch mit \u201eHillu\u201c Hiltrud verheiratet, und die ist Vegetarierin und weigerte sich, ihm zuhause Schnitzel und sowas zu braten.) Ich war ziemlich nerv\u00f6s und hatte Angst, ihm vielleicht aus Versehen die Nu-<br \/>deln in den Scho\u00df zu kippen. Zum Gl\u00fcck war wenigstens der Laden nicht so voll. Herr Schr\u00f6der war aber wider Erwarten ganz normal nett, geradezu sympathisch, ich beruhigte mich und er a\u00df in Ruhe seine Nudeln. <\/p>\n<p class=\"MsoNormal\">Da wusste ich ja zum Gl\u00fcck noch nicht, dass er mal Kanzler werden w\u00fcrde, sonst w\u00e4ren die Nudeln vor Aufregung <em>doch<\/em> sonstwo gelandet. Und wenn ich da schon gewusst h\u00e4tte, wie sehr er sich mal f\u00fcr \u201elupenreine\u201c Demokraten einsetzen w\u00fcrde, h\u00e4tte ich wom\u00f6glich sogar nachgeholfen. Nett hin oder her.<\/p>\n<p class=\"MsoNormal\">Herrn Trittin hingegen hatte ich ein paar Jahre zuvor als eher arrogant und herablassend empfunden. Das war die Zeit, als ich in der Markthalle einen ziemlich umfangreichen Delikatessenstand alleine schmei\u00dfen musste. Der Stand war ein Ableger eines franz\u00f6si-<br \/>schen Feinkostladens mit kleinem Restaurant. Samstags war immer die H\u00f6lle los, denn es kamen nicht nur mehr Kunden zum Einkaufen, sondern auch die M\u00f6chtegern-<em>Haute voll\u00e9e<\/em> zum Champagner-und-Schnittchen-Umtrunk. Da war der Herr Dosenpfand \u00f6fter mal mit seiner Entourage dabei und wollte nat\u00fcrlich immer alles sofort und pronto. Sollten die Anderen doch ruhig warten, und ich war ja eh\u2019 nur die Schnittchenmamsell. <\/p>\n<p>Ungef\u00e4hr zur selben Zeit tauchte dann auch die Albrecht-Familie mal im dazugeh\u00f6rigen Restaurant auf. Wir hatten sonntags dort ein kleines, aber feines Brunch-Buffet. Die Albrechts kamen, ich wei\u00df es nicht mehr genau, nicht ganz vollz\u00e4hlig, trotzdem sind es richtig viele gewesen. Schlie\u00dflich hatten wir ja auch noch ein paar andere G\u00e4ste. Buffet-<br \/>erfahren, wie die Albrechts waren, rasierten sie uns komplett, scheuchten uns getr\u00e4nke-<br \/>herbeikarrend durch die Gegend, aber vom typischen Albrecht-L\u00e4cheln war nix zu sehen. Eine knappe Dreiviertelstunde sp\u00e4ter war der Spuk vorbei, sie gingen so schnell, wie sie gekommen waren und lie\u00dfen uns ersch\u00f6pft zur\u00fcck. Danach zitterten wir jeden Sonntag, ob sie vielleicht noch mal k\u00e4men.<\/p>\n<p class=\"MsoNormal\">Mir war der ganze normale Betrieb ohne Promis immer viel lieber, und ich hab\u2019 mich \u00fcber meine ganz normalen, aber netten Stammg\u00e4ste viel mehr gefreut. Da fing der Chef auch nicht an, sich zu \u00fcberschlagen, es gab keinen Grund zur Nervosit\u00e4t und mehr Trinkgeld gab&#8217;s meistens noch dazu&#8230;<\/p>\n<p class=\"MsoNormal\">\u00a0<br \/>So, lieber Jules, <em>eine <\/em>Deiner Fragen habe ich nun noch \u00fcbrig; &#8211; die kommt dann wohl kurz vor Weihnachten dran. Mal gucken.<\/p>\n<p class=\"MsoNormal\">Bis dahin, <font color=\"#cc3333\"><strong>erstmal pinkgefiederte Gr\u00fc\u00dfe<\/strong><\/font>,<\/p>\n<p class=\"MsoNormal\">von <font color=\"#cc3333\"><strong>Theobromina<\/strong><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da auch Trithemius mir gleich ganz sch\u00f6n viele Fragen gestellt hat, fasse ich heute mal drei davon zusammen, denn das bietet sich geradezu an. Er m\u00f6chte n\u00e4mlich wissen: &#8222;Bist du Schr\u00f6der in Hannover schon begegnet?Was ist mit der Albrecht-Bagage? Und geisterte nicht auch Herr Dosenpfand in Hannover herum?&#8220;Antwort: Erstmal vorweg: &#8211; Wer Schr\u00f6der ist, wei\u00df [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[1],"tags":[4,5,10],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6SDtE-etMF","_links":{"self":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/3451085"}],"collection":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/comments?post=3451085"}],"version-history":[{"count":0,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/3451085\/revisions"}],"wp:attachment":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/media?parent=3451085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/categories?post=3451085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/tags?post=3451085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}