{"id":2404188,"date":"2007-06-06T11:44:07","date_gmt":"2007-06-06T11:44:07","guid":{"rendered":"http:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2007\/06\/06\/schokelaahde2404188\/"},"modified":"2007-06-06T11:44:07","modified_gmt":"2007-06-06T11:44:07","slug":"schokelaahde2404188","status":"publish","type":"post","link":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/2007\/06\/06\/schokelaahde2404188\/","title":{"rendered":"Schokelaahde"},"content":{"rendered":"<p>Ich hatte hier ja schon mal eine Schokohelden-Liste aufgestellt, aber ich muss mich nat\u00fcrlich noch ausf\u00fchrlicher dem Thema Schokoladismus widmen.<br \/>\nGrunds\u00e4tzlich: <strong>Schoki mag jeder!<\/strong><br \/>\nDas ist Gesetz.<br \/>\nWann immer ich auf Menschen traf, die Schokolade &#8222;gar nicht sooo&#8220; m\u00f6gen, war ich eher vorsichtig und das hat sich noch jedes Mal bew\u00e4hrt.<\/p>\n<p>Ich teile im Bekanntenkreis neu zugegangene Herrschaften gern nach ihren Vorlieben ein und ich muss sagen, das funktioniert gar nicht mal schlecht.<\/p>\n<p>Erste Frage: Marzipan oder Nougat?<br \/>\nDie meisten m\u00f6gen nur Eines und das Andere gar nicht, seltener sind Mischcharaktere, was entweder auf erweiterten Horizont oder Allesfresserei hindeutet.<\/p>\n<p>Sondergruppe: Bl\u00e4tterkrokant.<\/p>\n<p>Zweite Frage meistens: Lieblingsschokolade.<br \/>\nErstaunlich viele M\u00e4nner geben hier &#8222;Kinderschoki&#8220; an.<br \/>\nWarum, habe ich noch nicht rausgekriegt. Es kann was mit Phantasielosigkeit zu tun haben, der Angst Neues kennen zu lernen, dem &#8222;HausebeiMamigef\u00fchl&#8220; von fr\u00fcher, oderwattwei\u00dfichwomit.<br \/>\nVielleicht schmeckt sie ihnen einfach (mir \u00fcbrigens auch schomma, aber nur gelegentlich, und ich w\u00fcrde auch nicht unbedingt <em>Schokolade<\/em> dazu sagen).<br \/>\nM\u00e4nner m\u00f6gen aber auch gerne so Riesentafeln, wo man Maulsperre von kriegt (500g-Brett M*lka, Monstertobl*rone!). Es d\u00fcrfen auch gerne ganze Riesenn\u00fcsse drin sein. Wahrscheinlich, weil das irgendwie kernig ist, die wegzuarbeiten und man dann richtig was geschafft hat. So wie beim Holzhacken vielleicht.<\/p>\n<p>Frauen haben gerne so Sachen, die auch noch mal einzeln verpackt sind, weil es h\u00fcbscher aussieht. Auch zarte Joghurt- und Fruchtinhalte finden die M\u00e4dels oft gut. Und Verzierungen mit andersbrauner Schoko.<\/p>\n<p>Allgemein begr\u00fc\u00dfe ich den Trend zu hochwertigen Schokoladen sehr, bin aber immer wieder betr\u00fcbt, wenn ich sehe, wie mit diesem Trend von Seiten der Industrie umgegangen wird. Da werden Schokoladen als hochwertig verkauft, die mal grade einen hohen Kakaoanteil vorweisen k\u00f6nnen. Vorreiter der Verarsche ist meiner Meinung nach L*ndt, die immer so Confiseriem\u00e4\u00dfig-Feinschmeckerhaft tun und es aber nicht sind.<br \/>\nDas Einzige, was die echt gut k\u00f6nnen, ist Bl\u00e4tterkrokant, den es aber leider nur zu Ostern und zu Weihnachten gibt.<br \/>\n<u><br \/>\nAchtung! Jetzt Belehrung:<\/u><br \/>\nWichtiger Gradmesser ist die Zutatenliste, die allgemein erstaunlich wenig gelesen wird.<br \/>\nWenn da steht: Aroma: Vanillin, dann Finger weg! Da ist noch nicht mal richtige Vanille drin. Sollte aber.<\/p>\n<p>Doof auch: Emulgator: Sojalezithin. Das wird n\u00e4mlich gern aus Gensoja gewonnen. Es gibt aber einige Firmen, die auf Gensoja verzichten und nur normales Sojalezithin verwenden (Hachez. Feodora. Ritter bem\u00fcht sich.)<br \/>\nDaher sind Lezithinfreie Schokoladen vorzuziehen. Die sind aber im Supermarkt selten und wenn, dann teuer.<br \/>\nAuch bei dem Molke- Milch- und Sahnepulver wei\u00df man nie genau, wattie K\u00fche so zu Fressen hatten.<\/p>\n<p>In einer vern\u00fcnftigen Schoki sind m\u00f6glichst wenig Zutaten drin: Kakaomasse, Zucker, Kakaobutter, Vanille.<\/p>\n<p>Und dann probiert man sich so durch, bis man seine Lieblingssorte hat. Es muss ja keine Bitterschokolade sein, es gibt auch ganz bombige Vollmilchkollegen.<br \/>\nIch f\u00fcrchte, dass viele Schokoladen nach der Gestaltung der Verpackung oder der Werbung gekauft werden. Manch einer w\u00fcrde seinen Favoriten in der Blindverkostung wom\u00f6glich gar nicht wieder erkennen.<\/p>\n<p>Sachen mit lila Einwickelpapier, solche mit &#8222;Mohren&#8220; drauf oder so Klotzriegel buche ich pers\u00f6nlich unter &#8222;S\u00fc\u00dfigkeit&#8220; oder &#8222;Fastfood&#8220; ab, wo sie sich sehr wohl zu f\u00fchlen scheinen.<\/p>\n<p>Was \u00fcberhaupt nicht zu Schokolade zu z\u00e4hlen ist, ist &#8222;Wei\u00dfe Schokolade&#8220;. Im Grunde ist das nur Kakaobutter (und andere Fette), Zucker und was noch so weg musste. Dass das auch mal lecker sein kann, wenn man unterzuckert ist, ist nachvollziehbar.<br \/>\nAber Schoki ist es nicht. Keine Kakaomasse.<\/p>\n<p>In meinem Schrank liegt jedenfalls alles wild durcheinander: Feinstes Geschmeck neben ordin\u00e4rem Zuckerproll.<br \/>\nFeinstes Geschmeck wird mit Bedacht ausgepellt, beschnuppert, vorsichtig angekaut, zerlutscht und \u00fcberhaupt in Ruhe genossen.<br \/>\n(Ich k\u00f6nnte z.B. niemals einen Mann lieben, der sich feinste Tr\u00fcffel wie ordin\u00e4re Bulette in Kurzzeit hinter die Kiemen haut! Kretin! Ich selbst hab&#8216; nat\u00fcrlich eine Spezialtr\u00fcffelnaschtechnik.)<\/p>\n<p>Zuckerprolls werden hingegen auch mal aus der Packung gefetzt, dann wird auch mal direkt von der Tafel abgebissen, gemalmt und verschlungen. Das muss auch mal sein.<\/p>\n<p>Am Sch\u00f6nsten aber: Sonntagmorgen im Bett sitzen mit nettem Lesestoff und einer richtig guten Pralinenmischung und vielleicht einem Tee. Wenn dann der Nachbar nicht Gitarre spielt und das Telefon schweigt, h\u00f6rt man nur das sch\u00fcchterne Geknispel der Papiermanschettchen&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich hatte hier ja schon mal eine Schokohelden-Liste aufgestellt, aber ich muss mich nat\u00fcrlich noch ausf\u00fchrlicher dem Thema Schokoladismus widmen. Grunds\u00e4tzlich: Schoki mag jeder! Das ist Gesetz. Wann immer ich auf Menschen traf, die Schokolade &#8222;gar nicht sooo&#8220; m\u00f6gen, war ich eher vorsichtig und das hat sich noch jedes Mal bew\u00e4hrt. Ich teile im Bekanntenkreis [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[1],"tags":[12,15,25,8],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6SDtE-a5re","_links":{"self":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/2404188"}],"collection":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/comments?post=2404188"}],"version-history":[{"count":0,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/posts\/2404188\/revisions"}],"wp:attachment":[{"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/media?parent=2404188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/categories?post=2404188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theobromina.de\/100prozentig-selbst-erlebt\/wp-json\/wp\/v2\/tags?post=2404188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}